{"id":2229,"date":"2019-11-25T10:30:38","date_gmt":"2019-11-25T10:30:38","guid":{"rendered":"http:\/\/www.srt-partner.de\/?p=2229"},"modified":"2019-11-25T10:30:38","modified_gmt":"2019-11-25T10:30:38","slug":"kw-48-versendet-am-25-11-2019","status":"publish","type":"post","link":"https:\/\/www.srt-partner.de\/index.php\/kw-48-versendet-am-25-11-2019\/","title":{"rendered":"KW 48, versendet am 25.11.2019"},"content":{"rendered":"<p><strong>Jubil\u00e4en 2020: Von Australien bis zu den X-Strahlen. <\/strong><\/p>\n<p>Bahnbrechende Erfindungen, folgenreiche Ideen und moderne Kunst \u2013 diese zw\u00f6lf runden Geburtstage sind im kommenden Jahr eine Reise wert<\/p>\n<p><em>Von Sibylle von Kamptz<\/em> (5925 Zeichen \u2013 Bilder: <a href=\"http:\/\/www.srt-text.de\">www.srt-text.de<\/a>)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Nicht tr\u00e4umen \u2013 hinfahren: Unterwegs auf Neuseelands Nordinsel.<\/strong> Kaum ein Fleck auf der Welt vereint eine solche Vielfalt umwerfender Naturlandschaften \u2013 mit goldfarbenen Str\u00e4nden und saftig gr\u00fcnen Weiden und blau schimmernden Gletscherfeldern. Manchmal faucht sogar ein Vulkan<\/p>\n<p><em>Von Brigitte von Imhof<\/em> (5927 Zeichen \u2013 Bilder: www.srt-text.de)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Hygiene im Flugzeug: Keimherd Kopfst\u00fctze.<\/strong> Sie sieht so harmlos aus, dabei tummeln sich auf ihr Milliarden Krankheitserreger. Einfache<\/p>\n<p>Tipps mindern das Ansteckungsrisiko<\/p>\n<p><em>Von Tinga Horny<\/em> (3540 Zeichen \u2013 Bilder: <a href=\"http:\/\/www.srt-text.de\">www.srt-text.de<\/a>)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Skiurlaub auf der Lenzerheide: Sch\u00fcmli-Pfl\u00fcmli an der Sonnenterrasse.<\/strong> Ski-in, ski-out: In dem s\u00fcdseitig ge\u00f6ffneten Graub\u00fcndner Hochtal schwingt man von den meisten Unterk\u00fcnften direkt auf die Piste<\/p>\n<p><em>Von Hans-Werner Rodrian<\/em> (6305 Zeichen \u2013 Bilder: www.srt-text.de)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Genussland Istrien: Wein, Oliven\u00f6l und Tr\u00fcffel satt.<\/strong> Istrien ist mehr als nur ein Badeziel. Die kroatische Halbinsel empfiehlt sich als Genussland<\/p>\n<p>mit k\u00f6stlichen Sch\u00e4tzen<\/p>\n<p><em>Von Simone F. Lucas<\/em> (6399 Zeichen \u2013 Bilder: <a href=\"http:\/\/www.srt-text.de\">www.srt-text.de<\/a>)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Namibia: Poesie der Steinzeit.<\/strong> Ein ehemaliger Landvermesser entdeckt eine der gr\u00f6\u00dften Ansammlungen von Felskunst in Afrika \u2013 jetzt st\u00fcrzt sich die Forschung auf den kulturhistorischen Schatz<\/p>\n<p><em>Von Fabian von Poser<\/em> (4236 Zeichen \u2013 Bilder: www.srt-text.de)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Springfield in Illinois: Auf den Spuren von Abraham Lincoln.<\/strong> Der 16. Pr\u00e4sident verbrachte den Gro\u00dfteil seines Lebens in Springfield. Auf den Spuren eines der bekanntesten US-Pr\u00e4sidenten in der Hauptstadt von Illinois<\/p>\n<p><em>Von Karsten-Thilo Raab<\/em> (6783 Zeichen \u2013 Bilder: <a href=\"http:\/\/www.srt-text.de\">www.srt-text.de<\/a>)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Island: Schnorcheln zwischen den Kontinenten.<\/strong> Wegen ihrer klaren Sicht und den psychodelischen Blaut\u00f6nen z\u00e4hlt die isl\u00e4ndische Silfra-Spalte, wo zwei Kontinente auseinander driften, zu den aufregendsten Tauch- und Schnorchelspots der Welt \u2013 auch im Winter<\/p>\n<p><em>Von Christian Haas<\/em> (4443 Zeichen \u2013 Bilder: www.srt-text.de)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Passionsspiele Oberammergau: Jesus Christ Superstar.<\/strong> N\u00e4chstes Jahr ist es wieder so weit: Bei den Passionsspielen in Oberammergau wird zwischen Mai und Oktober fast eine halbe Million Besucher aus aller Welt erwartet. Im Dezember beginnen die Proben f\u00fcr die rund 2000 Mitwirkenden<\/p>\n<p><em>Von Klaus K\u00fchlewind<\/em> (7455 Zeichen \u2013 Bilder: <a href=\"http:\/\/www.srt-text.de\">www.srt-text.de<\/a>)<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Architektur am Berg: James Bond ist \u00fcberall.<\/strong> Im Alpenraum ersetzen hochmoderne Bauten in die Jahre gekommene Gipfelgeb\u00e4ude \u2013 ein<\/p>\n<p>Erlebnis f\u00fcr Architektur-Fans und Genie\u00dfer<\/p>\n<p><em>Von Monika Hoeksema<\/em> (8036 Zeichen \u2013 Bilder: <a href=\"http:\/\/www.srt-text.de\">www.srt-text.de<\/a>)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Von A(laska) bis Z(\u00fcrich): WorldWideWeihnachtsbaum.<\/strong> O Tannenbaum: Unter all den funkelnden Prachtst\u00fccken, die der Adventzeit ihren<\/p>\n<p>unvergleichlichen Zauber verleihen, gibt es besondere Hingucker<\/p>\n<p><em>Von Brigitte von Imhof<\/em> (5589 Zeichen \u2013 Bilder: www.srt-text.de)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>KURZ GEMELDET<\/strong><\/p>\n<p>Kreuzfahrt: MSC setzt auf Klimaneutralit\u00e4t<\/p>\n<p>Australien: Tropical Light in Darwin<\/p>\n<p>Malaga: Wandern im spanischen Herbst<\/p>\n<p>Wipptal: Mobil mit Bahn und Bus<\/p>\n<p>Tourismus: Positive Ausblicke f\u00fcr 2020<\/p>\n<p>Texel: Ein Albino-Seehund im Ecomare<\/p>\n<p>Oberammergau: Erste Proben f\u00fcr die Passionsspiele<\/p>\n<p>Winter: Kreativ im Schnee<\/p>\n<p>Bustouristik: Klimafreundlich in die Zukunft<\/p>\n<p>London: Es gr\u00fcnt so gr\u00fcn<\/p>\n<p>Olympia: Airbnb mit Olympischen Entdeckungen<\/p>\n<p>&nbsp;<\/p>\n<p><strong>BUCHBESPRECHUNG<\/strong><\/p>\n<p><strong>Georgien \u2013 kleines Land mit gro\u00dfer Vielfalt\u2028.<\/strong> Ein informativer Bildband widmet sich 50 spannenden Zielen in Georgien, dem Land im Kaukasus, das bei vielen die Reiselust weckt<\/p>\n<p><em>Von Simone F. Lucas<\/em> (2570 Zeichen \u2013 Bilder: www.srt-text.de)<\/p>\n<p>&nbsp;<\/p>\n<p><em>Textredakteurin dieser Woche war Brigitte von Imhof, Co-Redakteur Franz-Michael Rohm<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jubil\u00e4en 2020: Von Australien bis zu den X-Strahlen. Bahnbrechende Erfindungen, folgenreiche Ideen und moderne Kunst \u2013 diese zw\u00f6lf runden Geburtstage sind im kommenden Jahr eine Reise wert Von Sibylle von Kamptz (5925 Zeichen \u2013 Bilder: www.srt-text.de) &nbsp; Nicht tr\u00e4umen \u2013 hinfahren: Unterwegs auf Neuseelands Nordinsel. Kaum ein Fleck auf der<a href=\"https:\/\/www.srt-partner.de\/index.php\/kw-48-versendet-am-25-11-2019\/\" class=\"read-more\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-2229","post","type-post","status-publish","format-standard","hentry","category-texte"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Jubil\u00e4en 2020: Von Australien bis zu den X-Strahlen. Bahnbrechende Erfindungen, folgenreiche Ideen und moderne Kunst \u2013 diese zw\u00f6lf runden Geburtstage sind im kommenden Jahr eine Reise wert Von Sibylle von Kamptz (5925 Zeichen \u2013 Bilder: www.srt-text.de) Nicht tr\u00e4umen \u2013 hinfahren: Unterwegs auf Neuseelands Nordinsel. Kaum ein Fleck auf der Welt vereint eine solche Vielfalt\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"texte\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.srt-partner.de\/index.php\/kw-48-versendet-am-25-11-2019\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"SRT Partner | Hier erfahren Sie alles \u00fcber die SRT Journalisten-Partnerschaft\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"KW 48, versendet am 25.11.2019 | SRT Partner\" \/>\n\t\t<meta property=\"og:description\" content=\"Jubil\u00e4en 2020: Von Australien bis zu den X-Strahlen. Bahnbrechende Erfindungen, folgenreiche Ideen und moderne Kunst \u2013 diese zw\u00f6lf runden Geburtstage sind im kommenden Jahr eine Reise wert Von Sibylle von Kamptz (5925 Zeichen \u2013 Bilder: www.srt-text.de) Nicht tr\u00e4umen \u2013 hinfahren: Unterwegs auf Neuseelands Nordinsel. Kaum ein Fleck auf der Welt vereint eine solche Vielfalt\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.srt-partner.de\/index.php\/kw-48-versendet-am-25-11-2019\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-11-25T10:30:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-11-25T10:30:38+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"KW 48, versendet am 25.11.2019 | SRT Partner\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Jubil\u00e4en 2020: Von Australien bis zu den X-Strahlen. Bahnbrechende Erfindungen, folgenreiche Ideen und moderne Kunst \u2013 diese zw\u00f6lf runden Geburtstage sind im kommenden Jahr eine Reise wert Von Sibylle von Kamptz (5925 Zeichen \u2013 Bilder: www.srt-text.de) Nicht tr\u00e4umen \u2013 hinfahren: Unterwegs auf Neuseelands Nordinsel. Kaum ein Fleck auf der Welt vereint eine solche Vielfalt\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/kw-48-versendet-am-25-11-2019\\\/#article\",\"name\":\"KW 48, versendet am 25.11.2019 | SRT Partner\",\"headline\":\"KW 48, versendet am 25.11.2019\",\"author\":{\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/author\\\/texte\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/#organization\"},\"datePublished\":\"2019-11-25T10:30:38+00:00\",\"dateModified\":\"2019-11-25T10:30:38+00:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/kw-48-versendet-am-25-11-2019\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/kw-48-versendet-am-25-11-2019\\\/#webpage\"},\"articleSection\":\"texte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/kw-48-versendet-am-25-11-2019\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.srt-partner.de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.srt-partner.de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/category\\\/texte\\\/#listItem\",\"name\":\"texte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/category\\\/texte\\\/#listItem\",\"position\":2,\"name\":\"texte\",\"item\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/category\\\/texte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/kw-48-versendet-am-25-11-2019\\\/#listItem\",\"name\":\"KW 48, versendet am 25.11.2019\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.srt-partner.de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/kw-48-versendet-am-25-11-2019\\\/#listItem\",\"position\":3,\"name\":\"KW 48, versendet am 25.11.2019\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/category\\\/texte\\\/#listItem\",\"name\":\"texte\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/#organization\",\"name\":\"SRT Partner\",\"description\":\"Hier erfahren Sie alles \\u00fcber die SRT Journalisten-Partnerschaft\",\"url\":\"https:\\\/\\\/www.srt-partner.de\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/author\\\/texte\\\/#author\",\"url\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/author\\\/texte\\\/\",\"name\":\"texte\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/kw-48-versendet-am-25-11-2019\\\/#webpage\",\"url\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/kw-48-versendet-am-25-11-2019\\\/\",\"name\":\"KW 48, versendet am 25.11.2019 | SRT Partner\",\"description\":\"Jubil\\u00e4en 2020: Von Australien bis zu den X-Strahlen. Bahnbrechende Erfindungen, folgenreiche Ideen und moderne Kunst \\u2013 diese zw\\u00f6lf runden Geburtstage sind im kommenden Jahr eine Reise wert Von Sibylle von Kamptz (5925 Zeichen \\u2013 Bilder: www.srt-text.de) Nicht tr\\u00e4umen \\u2013 hinfahren: Unterwegs auf Neuseelands Nordinsel. Kaum ein Fleck auf der Welt vereint eine solche Vielfalt\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/kw-48-versendet-am-25-11-2019\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/author\\\/texte\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/author\\\/texte\\\/#author\"},\"datePublished\":\"2019-11-25T10:30:38+00:00\",\"dateModified\":\"2019-11-25T10:30:38+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/#website\",\"url\":\"https:\\\/\\\/www.srt-partner.de\\\/\",\"name\":\"SRT Partner\",\"description\":\"Hier erfahren Sie alles \\u00fcber die SRT Journalisten-Partnerschaft\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"KW 48, versendet am 25.11.2019 | SRT Partner","description":"Jubil\u00e4en 2020: Von Australien bis zu den X-Strahlen. Bahnbrechende Erfindungen, folgenreiche Ideen und moderne Kunst \u2013 diese zw\u00f6lf runden Geburtstage sind im kommenden Jahr eine Reise wert Von Sibylle von Kamptz (5925 Zeichen \u2013 Bilder: www.srt-text.de) Nicht tr\u00e4umen \u2013 hinfahren: Unterwegs auf Neuseelands Nordinsel. Kaum ein Fleck auf der Welt vereint eine solche Vielfalt","canonical_url":"https:\/\/www.srt-partner.de\/index.php\/kw-48-versendet-am-25-11-2019\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.srt-partner.de\/index.php\/kw-48-versendet-am-25-11-2019\/#article","name":"KW 48, versendet am 25.11.2019 | SRT Partner","headline":"KW 48, versendet am 25.11.2019","author":{"@id":"https:\/\/www.srt-partner.de\/index.php\/author\/texte\/#author"},"publisher":{"@id":"https:\/\/www.srt-partner.de\/#organization"},"datePublished":"2019-11-25T10:30:38+00:00","dateModified":"2019-11-25T10:30:38+00:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/www.srt-partner.de\/index.php\/kw-48-versendet-am-25-11-2019\/#webpage"},"isPartOf":{"@id":"https:\/\/www.srt-partner.de\/index.php\/kw-48-versendet-am-25-11-2019\/#webpage"},"articleSection":"texte"},{"@type":"BreadcrumbList","@id":"https:\/\/www.srt-partner.de\/index.php\/kw-48-versendet-am-25-11-2019\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.srt-partner.de#listItem","position":1,"name":"Home","item":"https:\/\/www.srt-partner.de","nextItem":{"@type":"ListItem","@id":"https:\/\/www.srt-partner.de\/index.php\/category\/texte\/#listItem","name":"texte"}},{"@type":"ListItem","@id":"https:\/\/www.srt-partner.de\/index.php\/category\/texte\/#listItem","position":2,"name":"texte","item":"https:\/\/www.srt-partner.de\/index.php\/category\/texte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.srt-partner.de\/index.php\/kw-48-versendet-am-25-11-2019\/#listItem","name":"KW 48, versendet am 25.11.2019"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.srt-partner.de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.srt-partner.de\/index.php\/kw-48-versendet-am-25-11-2019\/#listItem","position":3,"name":"KW 48, versendet am 25.11.2019","previousItem":{"@type":"ListItem","@id":"https:\/\/www.srt-partner.de\/index.php\/category\/texte\/#listItem","name":"texte"}}]},{"@type":"Organization","@id":"https:\/\/www.srt-partner.de\/#organization","name":"SRT Partner","description":"Hier erfahren Sie alles \u00fcber die SRT Journalisten-Partnerschaft","url":"https:\/\/www.srt-partner.de\/"},{"@type":"Person","@id":"https:\/\/www.srt-partner.de\/index.php\/author\/texte\/#author","url":"https:\/\/www.srt-partner.de\/index.php\/author\/texte\/","name":"texte"},{"@type":"WebPage","@id":"https:\/\/www.srt-partner.de\/index.php\/kw-48-versendet-am-25-11-2019\/#webpage","url":"https:\/\/www.srt-partner.de\/index.php\/kw-48-versendet-am-25-11-2019\/","name":"KW 48, versendet am 25.11.2019 | SRT Partner","description":"Jubil\u00e4en 2020: Von Australien bis zu den X-Strahlen. Bahnbrechende Erfindungen, folgenreiche Ideen und moderne Kunst \u2013 diese zw\u00f6lf runden Geburtstage sind im kommenden Jahr eine Reise wert Von Sibylle von Kamptz (5925 Zeichen \u2013 Bilder: www.srt-text.de) Nicht tr\u00e4umen \u2013 hinfahren: Unterwegs auf Neuseelands Nordinsel. Kaum ein Fleck auf der Welt vereint eine solche Vielfalt","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/www.srt-partner.de\/#website"},"breadcrumb":{"@id":"https:\/\/www.srt-partner.de\/index.php\/kw-48-versendet-am-25-11-2019\/#breadcrumblist"},"author":{"@id":"https:\/\/www.srt-partner.de\/index.php\/author\/texte\/#author"},"creator":{"@id":"https:\/\/www.srt-partner.de\/index.php\/author\/texte\/#author"},"datePublished":"2019-11-25T10:30:38+00:00","dateModified":"2019-11-25T10:30:38+00:00"},{"@type":"WebSite","@id":"https:\/\/www.srt-partner.de\/#website","url":"https:\/\/www.srt-partner.de\/","name":"SRT Partner","description":"Hier erfahren Sie alles \u00fcber die SRT Journalisten-Partnerschaft","inLanguage":"de-DE","publisher":{"@id":"https:\/\/www.srt-partner.de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"SRT Partner | Hier erfahren Sie alles \u00fcber die SRT Journalisten-Partnerschaft","og:type":"article","og:title":"KW 48, versendet am 25.11.2019 | SRT Partner","og:description":"Jubil\u00e4en 2020: Von Australien bis zu den X-Strahlen. Bahnbrechende Erfindungen, folgenreiche Ideen und moderne Kunst \u2013 diese zw\u00f6lf runden Geburtstage sind im kommenden Jahr eine Reise wert Von Sibylle von Kamptz (5925 Zeichen \u2013 Bilder: www.srt-text.de) Nicht tr\u00e4umen \u2013 hinfahren: Unterwegs auf Neuseelands Nordinsel. Kaum ein Fleck auf der Welt vereint eine solche Vielfalt","og:url":"https:\/\/www.srt-partner.de\/index.php\/kw-48-versendet-am-25-11-2019\/","article:published_time":"2019-11-25T10:30:38+00:00","article:modified_time":"2019-11-25T10:30:38+00:00","twitter:card":"summary","twitter:title":"KW 48, versendet am 25.11.2019 | SRT Partner","twitter:description":"Jubil\u00e4en 2020: Von Australien bis zu den X-Strahlen. Bahnbrechende Erfindungen, folgenreiche Ideen und moderne Kunst \u2013 diese zw\u00f6lf runden Geburtstage sind im kommenden Jahr eine Reise wert Von Sibylle von Kamptz (5925 Zeichen \u2013 Bilder: www.srt-text.de) Nicht tr\u00e4umen \u2013 hinfahren: Unterwegs auf Neuseelands Nordinsel. Kaum ein Fleck auf der Welt vereint eine solche Vielfalt"},"aioseo_meta_data":{"post_id":"2229","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-21 06:17:10","updated":"2025-06-04 08:13:46","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.srt-partner.de\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.srt-partner.de\/index.php\/category\/texte\/\" title=\"texte\">texte<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tKW 48, versendet am 25.11.2019\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.srt-partner.de"},{"label":"texte","link":"https:\/\/www.srt-partner.de\/index.php\/category\/texte\/"},{"label":"KW 48, versendet am 25.11.2019","link":"https:\/\/www.srt-partner.de\/index.php\/kw-48-versendet-am-25-11-2019\/"}],"_links":{"self":[{"href":"https:\/\/www.srt-partner.de\/index.php\/wp-json\/wp\/v2\/posts\/2229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.srt-partner.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.srt-partner.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.srt-partner.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.srt-partner.de\/index.php\/wp-json\/wp\/v2\/comments?post=2229"}],"version-history":[{"count":1,"href":"https:\/\/www.srt-partner.de\/index.php\/wp-json\/wp\/v2\/posts\/2229\/revisions"}],"predecessor-version":[{"id":2230,"href":"https:\/\/www.srt-partner.de\/index.php\/wp-json\/wp\/v2\/posts\/2229\/revisions\/2230"}],"wp:attachment":[{"href":"https:\/\/www.srt-partner.de\/index.php\/wp-json\/wp\/v2\/media?parent=2229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.srt-partner.de\/index.php\/wp-json\/wp\/v2\/categories?post=2229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.srt-partner.de\/index.php\/wp-json\/wp\/v2\/tags?post=2229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}