{"id":2232,"date":"2019-12-02T09:57:51","date_gmt":"2019-12-02T09:57:51","guid":{"rendered":"http:\/\/www.srt-partner.de\/?p=2232"},"modified":"2019-12-04T11:36:26","modified_gmt":"2019-12-04T11:36:26","slug":"kw-49-versendet-am-02-12-2019","status":"publish","type":"post","link":"https:\/\/www.srt-partner.de\/index.php\/kw-49-versendet-am-02-12-2019\/","title":{"rendered":"KW 49, versendet am 02.12.2019"},"content":{"rendered":"<p><strong>Wintertipp Indoor-Camping: \u00dcberdachtes Campergl\u00fcck. <\/strong>Im Freien zu campen ist im Winter nur was f\u00fcr die wirklich Harten. F\u00fcr alle anderen gibt es eine coole Alternative: Indoor-Campingpl\u00e4tze. Dort wohnt man in meist liebevoll hergerichteten Oldtimer-Wohnwagen in aufgelassenen Fabrik- oder Lagerhallen. Aber kommt da auch wirklich das richtige Camping-Feeling auf?<\/p>\n<p><em>Von Hans-Werner Rodrian <\/em>(4853 Zeichen \u2013 Bilder: <a href=\"http:\/\/www.srt-text.de\">www.srt-text.de<\/a>)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Papua-Neuguinea: Der See der Monster. <\/strong>Der Lake Murray im Westen Papua-Neuguineas ist fast viermal so gro\u00df wie der Bodensee \u2013 ein Binnenmeer, an dem es keine Stra\u00dfen gibt und nur wenige Menschen. Daf\u00fcr soll dort ein Monster hausen<\/p>\n<p><em>Von Fabian von Poser <\/em>(7426 Zeichen \u2013 Bilder: <a href=\"http:\/\/www.srt-text.de\">www.srt-text.de<\/a>)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Paris im Advent: So sch\u00f6n glitzert Weihnachten. <\/strong>Aus der Stadt der Liebe wird in der Vorweihnachtszeit die Stadt der Lichter. Es glitzert von B\u00e4umen und \u00fcber Avenuen, Schaufenster erstrahlen fantasievoll und die rastlosen Pariser scheinen einen Gang zur\u00fcckzuschalten \u2013 zumindest auf dem Weihnachtsmarkt<\/p>\n<p><em>Von Sandra Ehegartner <\/em>(5952 Zeichen \u2013 Bilder: <a href=\"http:\/\/www.srt-text.de\">www.srt-text.de<\/a>)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Urlaubstrends 2020: Ablasshandel, Deutschlandurlaub, Undertourism. <\/strong>Wohin geht die Reise? Der Klimawandel hat die Reisebranche fest im Griff. Doch trotz Greta, Flugscham und h\u00f6heren Flugsteuern werden wir weiterhin verreisen. Die wichtigsten Trends des kommenden Jahres auf einen Blick<\/p>\n<p><em>Von Tinga Horny <\/em>(5215 Zeichen \u2013 Bilder: <a href=\"http:\/\/www.srt-text.de\">www.srt-text.de<\/a>)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Abu Dhabi: Sand, Strand und ein bisschen Kunst. <\/strong>Auf Saadiyat Island soll ein gro\u00dfes Kunstviertel mit drei Weltklasse-Museen entstehen. Doch bisher ist nur der Louvre Abu Dhabi er\u00f6ffnet. Auf die gro\u00dfe Kunst m\u00fcssen Urlauber also noch warten, daf\u00fcr bietet ihnen die Sandinsel sch\u00f6ne Str\u00e4nde ohne Ende<\/p>\n<p><em>Von B\u00e4rbel Schwertfeger \u00a0<\/em>(5168 Zeichen \u2013 Bilder: <a href=\"http:\/\/www.srt-text.de\">www.srt-text.de<\/a>)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Wandertipp f\u00fcr Alleinreisende: Winter-Auszeit auf La Gomera. <\/strong>Wer gerne die Wanderschuhe schn\u00fcrt, der ist auf La Gomera genau richtig. Wem daf\u00fcr die passende Begleitung fehlt, der schlie\u00dft sich einer Gruppe Alleinreisender an. Denn gemeinsam machen Trekkingtouren und Yoga zum Sonnenuntergang einfach mehr Spa\u00df<\/p>\n<p><em>Von Sabine Metzger \u00a0<\/em>(6731 Zeichen \u2013 Bilder: <a href=\"http:\/\/www.srt-text.de\">www.srt-text.de<\/a>)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Winterbummel in Dresden: Vom Striezelmarkt ins Prunk-Schlafzimmer. <\/strong>Trotz des spektakul\u00e4ren Kunstraubs: Dresden bietet zur Adventszeit eine einzigartige Atmosph\u00e4re &#8211; mit Weihnachtsmarkt, Residenzschloss und der lebhaften Neustadt<\/p>\n<p><em>Von Franz Michael Rohm <\/em>(3459 Zeichen \u2013 Bilder: <a href=\"http:\/\/www.srt-text.de\">www.srt-text.de<\/a>)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Wracktauchen der besonderen Art: Tauchgang ins Cockpit. <\/strong>Im Herbst wurde in Bahrain der gr\u00f6\u00dfte Unterwasserpark der Welt eingeweiht. Dessen Haupt-Tauchattraktion ist eine ausgemusterte Boeing 747. Wir verraten, wo Taucher sonst noch Flugzeuge unter Wasser anpeilen k\u00f6nnen<\/p>\n<p><em>Von Christian Haas <\/em>(2742 Zeichen \u2013 Bilder: <a href=\"http:\/\/www.srt-text.de\">www.srt-text.de<\/a>)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Flugversicherungen: Hier gibt\u2019s Geld, wenn der Flieger zu sp\u00e4t ankommt<\/strong><\/p>\n<p>So schlie\u00dfen Passagiere schnell und unkompliziert Policen ab, die bei Flugausf\u00e4llen oder Umleitung zu einem anderen Airport finanzielle Entsch\u00e4digungen zahlen<\/p>\n<p><em>Von Marc Reisner <\/em>(3201 Zeichen \u2013 Bilder: <a href=\"http:\/\/www.srt-text.de\">www.srt-text.de<\/a>)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>K\u00f6stliches Menorca: Gehaltvolle Saucen und ein balearischer Gin. <\/strong>Mallorcas kleine Schwester, aus deren Hauptstadt Mahon angeblich die Mayonnaise stammt, wartet noch mit anderen Besonderheiten auf \u2013 nicht nur kulinarischer Art<\/p>\n<p><em>Von Armin Herb <\/em>(5893 Zeichen \u2013 Bilder: <a href=\"http:\/\/www.srt-text.de\">www.srt-text.de<\/a>)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Winterspa\u00df f\u00fcr Familien: Gro\u00dfe Abfahrt f\u00fcr kleines Budget. <\/strong>Mit attraktiven Angeboten ist der Skiurlaub auch f\u00fcr Eltern mit Kindern ein erschwingliches Vergn\u00fcgen<\/p>\n<p><em>Von Heidi Siefert <\/em>(5878 Zeichen \u2013 Bilder: <a href=\"http:\/\/www.srt-text.de\">www.srt-text.de<\/a>)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Israel: K\u00f6nig Herodes und die Weihnachtslegende.<\/strong> Die Bibel machte ihn zum Kinderm\u00f6rder von Bethlehem &#8211; wohl zu Unrecht. Brutal war er, aber auch ein Vision\u00e4r, der monumentale Tempel, Pal\u00e4ste und Festungen f\u00fcr die Ewigkeit hinterlie\u00df. Eine vorweihnachtliche Spurensuche<br \/>\n<em>Von Angela B\u00f6hm (5815 Zeichen \u2013 Bilder: <a href=\"http:\/\/www.srt-text.de\">www.srt-text.de<\/a>)<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ski-Ziele mit dem Plus an Komfort: Bequem aufw\u00e4rts, total entspannt abw\u00e4rts.\u00a0<\/strong>Neue Lifte werden alpenweit stets mit dem Komfort-Argument beworben. Wo der Standard am h\u00f6chsten ist und wo auch das Abfahren ohne Stress m\u00f6glich ist<\/p>\n<p><em>Von Christoph Schrahe<\/em> <em>(7141 Zeichen \u2013 Bilder: <a href=\"http:\/\/www.srt-text.de\">www.srt-text.de<\/a>)<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>KURZ GEMELDET<\/strong><\/p>\n<p>Australien: Neuer Nationalpark<\/p>\n<p>Monaco: Neuer Stadtteil auf dem Meer<\/p>\n<p>Toulouse: Mehr Natur in der Stadt<\/p>\n<p>Trentino: Skigebiet ohne Plastik<\/p>\n<p>Luftfahrt: TUIfly geht auf die Langstrecke<\/p>\n<p>Tourismuspreis: Innovative Ideen ausgezeichnet<\/p>\n<p>China: Fingerabdruck bei der Einreise<\/p>\n<p>Dengue-Fieber: 1206 Todesopfer in Lateinamerika<\/p>\n<p>Fort Lauderdale: Ein Hotel in Gitarrenform<\/p>\n<p>Augsburg: Ofenhaus erh\u00e4lt Architektur-Auszeichnung<\/p>\n<p>Bamberg: Krippentour in der Stadt<\/p>\n<p>Deutschland: Als Marke un\u00fcbertroffen<\/p>\n<p>&nbsp;<\/p>\n<p><strong>BUCHBESPRECHUNG<\/strong><\/p>\n<p><strong>Herbergssuche in New York . <\/strong>Ein junges Paar beschreibt in dem Buch Stadtnomaden, \u201ewie wir in New York eine Wohnung suchten und ein neues Leben fanden\u201c<\/p>\n<p><em>Von Simone F. Lucas<\/em> (2267 Zeichen \u2013 Bilder:<a href=\"http:\/\/www.srt-text.de\/\"> www.srt-text.de<\/a>)<\/p>\n<p>&nbsp;<\/p>\n<p><em>Textredakteur dieser Woche war Rudi Stallein, Co-Redakteurin Sybille Boolakee und Bildredakteur Rainer Krause<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wintertipp Indoor-Camping: \u00dcberdachtes Campergl\u00fcck. Im Freien zu campen ist im Winter nur was f\u00fcr die wirklich Harten. F\u00fcr alle anderen gibt es eine coole Alternative: Indoor-Campingpl\u00e4tze. Dort wohnt man in meist liebevoll hergerichteten Oldtimer-Wohnwagen in aufgelassenen Fabrik- oder Lagerhallen. Aber kommt da auch wirklich das richtige Camping-Feeling auf? Von Hans-Werner<a href=\"https:\/\/www.srt-partner.de\/index.php\/kw-49-versendet-am-02-12-2019\/\" class=\"read-more\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-2232","post","type-post","status-publish","format-standard","hentry","category-texte"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Wintertipp Indoor-Camping: \u00dcberdachtes Campergl\u00fcck. Im Freien zu campen ist im Winter nur was f\u00fcr die wirklich Harten. F\u00fcr alle anderen gibt es eine coole Alternative: Indoor-Campingpl\u00e4tze. Dort wohnt man in meist liebevoll hergerichteten Oldtimer-Wohnwagen in aufgelassenen Fabrik- oder Lagerhallen. Aber kommt da auch wirklich das richtige Camping-Feeling auf? Von Hans-Werner Rodrian (4853 Zeichen \u2013 Bilder:\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"texte\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.srt-partner.de\/index.php\/kw-49-versendet-am-02-12-2019\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"SRT Partner | Hier erfahren Sie alles \u00fcber die SRT Journalisten-Partnerschaft\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"KW 49, versendet am 02.12.2019 | SRT Partner\" \/>\n\t\t<meta property=\"og:description\" content=\"Wintertipp Indoor-Camping: \u00dcberdachtes Campergl\u00fcck. Im Freien zu campen ist im Winter nur was f\u00fcr die wirklich Harten. F\u00fcr alle anderen gibt es eine coole Alternative: Indoor-Campingpl\u00e4tze. Dort wohnt man in meist liebevoll hergerichteten Oldtimer-Wohnwagen in aufgelassenen Fabrik- oder Lagerhallen. Aber kommt da auch wirklich das richtige Camping-Feeling auf? Von Hans-Werner Rodrian (4853 Zeichen \u2013 Bilder:\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.srt-partner.de\/index.php\/kw-49-versendet-am-02-12-2019\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-12-02T09:57:51+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-12-04T11:36:26+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"KW 49, versendet am 02.12.2019 | SRT Partner\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Wintertipp Indoor-Camping: \u00dcberdachtes Campergl\u00fcck. Im Freien zu campen ist im Winter nur was f\u00fcr die wirklich Harten. F\u00fcr alle anderen gibt es eine coole Alternative: Indoor-Campingpl\u00e4tze. Dort wohnt man in meist liebevoll hergerichteten Oldtimer-Wohnwagen in aufgelassenen Fabrik- oder Lagerhallen. Aber kommt da auch wirklich das richtige Camping-Feeling auf? Von Hans-Werner Rodrian (4853 Zeichen \u2013 Bilder:\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/kw-49-versendet-am-02-12-2019\\\/#article\",\"name\":\"KW 49, versendet am 02.12.2019 | SRT Partner\",\"headline\":\"KW 49, versendet am 02.12.2019\",\"author\":{\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/author\\\/texte\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/#organization\"},\"datePublished\":\"2019-12-02T09:57:51+00:00\",\"dateModified\":\"2019-12-04T11:36:26+00:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/kw-49-versendet-am-02-12-2019\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/kw-49-versendet-am-02-12-2019\\\/#webpage\"},\"articleSection\":\"texte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/kw-49-versendet-am-02-12-2019\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.srt-partner.de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.srt-partner.de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/category\\\/texte\\\/#listItem\",\"name\":\"texte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/category\\\/texte\\\/#listItem\",\"position\":2,\"name\":\"texte\",\"item\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/category\\\/texte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/kw-49-versendet-am-02-12-2019\\\/#listItem\",\"name\":\"KW 49, versendet am 02.12.2019\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.srt-partner.de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/kw-49-versendet-am-02-12-2019\\\/#listItem\",\"position\":3,\"name\":\"KW 49, versendet am 02.12.2019\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/category\\\/texte\\\/#listItem\",\"name\":\"texte\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/#organization\",\"name\":\"SRT Partner\",\"description\":\"Hier erfahren Sie alles \\u00fcber die SRT Journalisten-Partnerschaft\",\"url\":\"https:\\\/\\\/www.srt-partner.de\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/author\\\/texte\\\/#author\",\"url\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/author\\\/texte\\\/\",\"name\":\"texte\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/kw-49-versendet-am-02-12-2019\\\/#webpage\",\"url\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/kw-49-versendet-am-02-12-2019\\\/\",\"name\":\"KW 49, versendet am 02.12.2019 | SRT Partner\",\"description\":\"Wintertipp Indoor-Camping: \\u00dcberdachtes Campergl\\u00fcck. Im Freien zu campen ist im Winter nur was f\\u00fcr die wirklich Harten. F\\u00fcr alle anderen gibt es eine coole Alternative: Indoor-Campingpl\\u00e4tze. Dort wohnt man in meist liebevoll hergerichteten Oldtimer-Wohnwagen in aufgelassenen Fabrik- oder Lagerhallen. Aber kommt da auch wirklich das richtige Camping-Feeling auf? Von Hans-Werner Rodrian (4853 Zeichen \\u2013 Bilder:\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/kw-49-versendet-am-02-12-2019\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/author\\\/texte\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/index.php\\\/author\\\/texte\\\/#author\"},\"datePublished\":\"2019-12-02T09:57:51+00:00\",\"dateModified\":\"2019-12-04T11:36:26+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/#website\",\"url\":\"https:\\\/\\\/www.srt-partner.de\\\/\",\"name\":\"SRT Partner\",\"description\":\"Hier erfahren Sie alles \\u00fcber die SRT Journalisten-Partnerschaft\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.srt-partner.de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"KW 49, versendet am 02.12.2019 | SRT Partner","description":"Wintertipp Indoor-Camping: \u00dcberdachtes Campergl\u00fcck. Im Freien zu campen ist im Winter nur was f\u00fcr die wirklich Harten. F\u00fcr alle anderen gibt es eine coole Alternative: Indoor-Campingpl\u00e4tze. Dort wohnt man in meist liebevoll hergerichteten Oldtimer-Wohnwagen in aufgelassenen Fabrik- oder Lagerhallen. Aber kommt da auch wirklich das richtige Camping-Feeling auf? Von Hans-Werner Rodrian (4853 Zeichen \u2013 Bilder:","canonical_url":"https:\/\/www.srt-partner.de\/index.php\/kw-49-versendet-am-02-12-2019\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.srt-partner.de\/index.php\/kw-49-versendet-am-02-12-2019\/#article","name":"KW 49, versendet am 02.12.2019 | SRT Partner","headline":"KW 49, versendet am 02.12.2019","author":{"@id":"https:\/\/www.srt-partner.de\/index.php\/author\/texte\/#author"},"publisher":{"@id":"https:\/\/www.srt-partner.de\/#organization"},"datePublished":"2019-12-02T09:57:51+00:00","dateModified":"2019-12-04T11:36:26+00:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/www.srt-partner.de\/index.php\/kw-49-versendet-am-02-12-2019\/#webpage"},"isPartOf":{"@id":"https:\/\/www.srt-partner.de\/index.php\/kw-49-versendet-am-02-12-2019\/#webpage"},"articleSection":"texte"},{"@type":"BreadcrumbList","@id":"https:\/\/www.srt-partner.de\/index.php\/kw-49-versendet-am-02-12-2019\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.srt-partner.de#listItem","position":1,"name":"Home","item":"https:\/\/www.srt-partner.de","nextItem":{"@type":"ListItem","@id":"https:\/\/www.srt-partner.de\/index.php\/category\/texte\/#listItem","name":"texte"}},{"@type":"ListItem","@id":"https:\/\/www.srt-partner.de\/index.php\/category\/texte\/#listItem","position":2,"name":"texte","item":"https:\/\/www.srt-partner.de\/index.php\/category\/texte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.srt-partner.de\/index.php\/kw-49-versendet-am-02-12-2019\/#listItem","name":"KW 49, versendet am 02.12.2019"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.srt-partner.de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.srt-partner.de\/index.php\/kw-49-versendet-am-02-12-2019\/#listItem","position":3,"name":"KW 49, versendet am 02.12.2019","previousItem":{"@type":"ListItem","@id":"https:\/\/www.srt-partner.de\/index.php\/category\/texte\/#listItem","name":"texte"}}]},{"@type":"Organization","@id":"https:\/\/www.srt-partner.de\/#organization","name":"SRT Partner","description":"Hier erfahren Sie alles \u00fcber die SRT Journalisten-Partnerschaft","url":"https:\/\/www.srt-partner.de\/"},{"@type":"Person","@id":"https:\/\/www.srt-partner.de\/index.php\/author\/texte\/#author","url":"https:\/\/www.srt-partner.de\/index.php\/author\/texte\/","name":"texte"},{"@type":"WebPage","@id":"https:\/\/www.srt-partner.de\/index.php\/kw-49-versendet-am-02-12-2019\/#webpage","url":"https:\/\/www.srt-partner.de\/index.php\/kw-49-versendet-am-02-12-2019\/","name":"KW 49, versendet am 02.12.2019 | SRT Partner","description":"Wintertipp Indoor-Camping: \u00dcberdachtes Campergl\u00fcck. Im Freien zu campen ist im Winter nur was f\u00fcr die wirklich Harten. F\u00fcr alle anderen gibt es eine coole Alternative: Indoor-Campingpl\u00e4tze. Dort wohnt man in meist liebevoll hergerichteten Oldtimer-Wohnwagen in aufgelassenen Fabrik- oder Lagerhallen. Aber kommt da auch wirklich das richtige Camping-Feeling auf? Von Hans-Werner Rodrian (4853 Zeichen \u2013 Bilder:","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/www.srt-partner.de\/#website"},"breadcrumb":{"@id":"https:\/\/www.srt-partner.de\/index.php\/kw-49-versendet-am-02-12-2019\/#breadcrumblist"},"author":{"@id":"https:\/\/www.srt-partner.de\/index.php\/author\/texte\/#author"},"creator":{"@id":"https:\/\/www.srt-partner.de\/index.php\/author\/texte\/#author"},"datePublished":"2019-12-02T09:57:51+00:00","dateModified":"2019-12-04T11:36:26+00:00"},{"@type":"WebSite","@id":"https:\/\/www.srt-partner.de\/#website","url":"https:\/\/www.srt-partner.de\/","name":"SRT Partner","description":"Hier erfahren Sie alles \u00fcber die SRT Journalisten-Partnerschaft","inLanguage":"de-DE","publisher":{"@id":"https:\/\/www.srt-partner.de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"SRT Partner | Hier erfahren Sie alles \u00fcber die SRT Journalisten-Partnerschaft","og:type":"article","og:title":"KW 49, versendet am 02.12.2019 | SRT Partner","og:description":"Wintertipp Indoor-Camping: \u00dcberdachtes Campergl\u00fcck. Im Freien zu campen ist im Winter nur was f\u00fcr die wirklich Harten. F\u00fcr alle anderen gibt es eine coole Alternative: Indoor-Campingpl\u00e4tze. Dort wohnt man in meist liebevoll hergerichteten Oldtimer-Wohnwagen in aufgelassenen Fabrik- oder Lagerhallen. Aber kommt da auch wirklich das richtige Camping-Feeling auf? Von Hans-Werner Rodrian (4853 Zeichen \u2013 Bilder:","og:url":"https:\/\/www.srt-partner.de\/index.php\/kw-49-versendet-am-02-12-2019\/","article:published_time":"2019-12-02T09:57:51+00:00","article:modified_time":"2019-12-04T11:36:26+00:00","twitter:card":"summary","twitter:title":"KW 49, versendet am 02.12.2019 | SRT Partner","twitter:description":"Wintertipp Indoor-Camping: \u00dcberdachtes Campergl\u00fcck. Im Freien zu campen ist im Winter nur was f\u00fcr die wirklich Harten. F\u00fcr alle anderen gibt es eine coole Alternative: Indoor-Campingpl\u00e4tze. Dort wohnt man in meist liebevoll hergerichteten Oldtimer-Wohnwagen in aufgelassenen Fabrik- oder Lagerhallen. Aber kommt da auch wirklich das richtige Camping-Feeling auf? Von Hans-Werner Rodrian (4853 Zeichen \u2013 Bilder:"},"aioseo_meta_data":{"post_id":"2232","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-21 06:17:10","updated":"2025-06-04 08:13:46","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.srt-partner.de\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.srt-partner.de\/index.php\/category\/texte\/\" title=\"texte\">texte<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tKW 49, versendet am 02.12.2019\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.srt-partner.de"},{"label":"texte","link":"https:\/\/www.srt-partner.de\/index.php\/category\/texte\/"},{"label":"KW 49, versendet am 02.12.2019","link":"https:\/\/www.srt-partner.de\/index.php\/kw-49-versendet-am-02-12-2019\/"}],"_links":{"self":[{"href":"https:\/\/www.srt-partner.de\/index.php\/wp-json\/wp\/v2\/posts\/2232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.srt-partner.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.srt-partner.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.srt-partner.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.srt-partner.de\/index.php\/wp-json\/wp\/v2\/comments?post=2232"}],"version-history":[{"count":3,"href":"https:\/\/www.srt-partner.de\/index.php\/wp-json\/wp\/v2\/posts\/2232\/revisions"}],"predecessor-version":[{"id":2236,"href":"https:\/\/www.srt-partner.de\/index.php\/wp-json\/wp\/v2\/posts\/2232\/revisions\/2236"}],"wp:attachment":[{"href":"https:\/\/www.srt-partner.de\/index.php\/wp-json\/wp\/v2\/media?parent=2232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.srt-partner.de\/index.php\/wp-json\/wp\/v2\/categories?post=2232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.srt-partner.de\/index.php\/wp-json\/wp\/v2\/tags?post=2232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}